{"id":20370,"date":"2023-10-13T11:56:09","date_gmt":"2023-10-13T18:56:09","guid":{"rendered":"https:\/\/www.opalco.com\/?p=20370"},"modified":"2023-10-13T11:56:49","modified_gmt":"2023-10-13T18:56:49","slug":"accion-climatica","status":"publish","type":"post","link":"https:\/\/www.opalco.com\/es\/climate-action\/2023\/10\/","title":{"rendered":"Acci\u00f3n clim\u00e1tica en el condado de San Juan"},"content":{"rendered":"<p>El Instituto Madrona ha organizado una excelente serie de oradores sobre acci\u00f3n clim\u00e1tica. El 12 de octubre, la serie de oradores cont\u00f3 con las palabras de apertura de la Senadora Liz Lovelett, seguidas por Jay Kimball, vicepresidente del Comit\u00e9 Asesor sobre Sostenibilidad y Clima del Condado de San Juan, hablando sobre la acci\u00f3n clim\u00e1tica del Condado, y Vince Dauciunas, presidente de la Junta de OPALCO, hablando sobre la resiliencia. sistemas energ\u00e9ticos.<\/p>\n<p>El senador Lovelett ofreci\u00f3 una descripci\u00f3n general de las acciones clim\u00e1ticas legislativas estatales que est\u00e1n en progreso o bajo revisi\u00f3n. Destac\u00f3 un viaje que hizo a Escandinavia para aprender sobre la acci\u00f3n clim\u00e1tica y las mejores pr\u00e1cticas sostenibles que pueden informar la estrategia clim\u00e1tica del estado de Washington. Tambi\u00e9n elogi\u00f3 el liderazgo de futuro de OPALCO para preparar la red para las nuevas cargas provenientes de la electrificaci\u00f3n del transporte y la calefacci\u00f3n.<\/p>\n<p>Sobre la base de este tema de la acci\u00f3n clim\u00e1tica, Jay Kimball destac\u00f3 las megatendencias globales que est\u00e1n impulsando un r\u00e1pido cambio hacia emisiones netas cero. Al revisar los objetivos clim\u00e1ticos nacionales y estatales, destac\u00f3 el reciente estudio de emisiones de gases de efecto invernadero (GEI) del condado de San Juan que muestra que m\u00e1s de 80% de GEI provienen de solo dos cosas: transporte y calefacci\u00f3n. Repas\u00f3 c\u00f3mo otras comunidades isle\u00f1as est\u00e1n innovando nuevos enfoques para el transporte p\u00fablico limpio y mostr\u00f3 c\u00f3mo, trabajando con nuestros condados vecinos, una red de transporte p\u00fablico unificada podr\u00eda proporcionar un transporte limpio conveniente, asequible y accesible para la regi\u00f3n.<\/p>\n<p>Vince Dauciunas mostr\u00f3 c\u00f3mo el estado est\u00e1 contemplando la transici\u00f3n del sistema energ\u00e9tico regional a cero emisiones netas para 2050. Destac\u00f3 de d\u00f3nde proviene nuestra energ\u00eda y el complejo conjunto de desaf\u00edos que surgen a medida que se implementan sistemas de transmisi\u00f3n y energ\u00eda e\u00f3lica y solar con uso intensivo de tierra para cumplir con la duplicaci\u00f3n esperada de la carga el\u00e9ctrica. Luego pas\u00f3 al panorama energ\u00e9tico local, revisando la capacidad solar y e\u00f3lica en el condado, mostrando c\u00f3mo la energ\u00eda de las mareas puede ser nuestra mejor energ\u00eda local para la producci\u00f3n durante todo el a\u00f1o. Para minimizar la cantidad de energ\u00eda nueva que desarrollamos, Vince destac\u00f3 Switch It Up! de OPALCO. programa, que ayuda a los miembros de la cooperativa a mejorar su eficiencia energ\u00e9tica con financiamiento asequible en la factura para bombas de calor, aislamiento, ventanas, energ\u00eda solar y almacenamiento de bater\u00edas.<\/p>\n<p>Las presentaciones de Jay y Vince est\u00e1n disponibles en los enlaces a continuaci\u00f3n. El Instituto Madrona publicar\u00e1 un enlace al v\u00eddeo del evento. Incluimos un enlace a toda su serie de oradores, que animamos a los lectores a consultar.<\/p>\n<p>Presentaci\u00f3n de Jay: <a href=\"https:\/\/www.opalco.com\/wp-content\/uploads\/2023\/10\/Climate-Solutions-Jay-Kimball-20231012.pdf\">Acci\u00f3n clim\u00e1tica en el condado de San Juan<\/a><\/p>\n<p>La presentaci\u00f3n de Vince: <a href=\"https:\/\/www.opalco.com\/wp-content\/uploads\/2023\/10\/Oct-11-FHL-Presentation.pdf\">Sistemas de energ\u00eda resilientes<\/a><\/p>\n<p>V\u00eddeos de la serie de oradores del Instituto Madrona: https:\/\/www.youtube.com\/@TheMadronaInstitute\/videos<\/p>","protected":false},"excerpt":{"rendered":"<p>El Instituto Madrona ha organizado una excelente serie de oradores sobre acci\u00f3n clim\u00e1tica. El 12 de octubre, la serie de oradores cont\u00f3 con las palabras de apertura de la senadora Liz Lovelett, seguida de Jay Kimball, vice... <a class=\"co-blog_post--morelink\" href=\"https:\/\/www.opalco.com\/es\/climate-action\/2023\/10\/\" aria-label=\"Leer m\u00e1s sobre: Acci\u00f3n Clim\u00e1tica en el Condado de San Juan\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":34,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[648],"tags":[],"class_list":["post-20370","post","type-post","status-publish","format-standard","hentry","category-energy-policy-renewable-energy"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Climate Action in San Juan County - OPALCO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.opalco.com\/es\/accion-climatica\/2023\/10\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Climate Action in San Juan County - OPALCO\" \/>\n<meta property=\"og:description\" content=\"The Madrona Institute has been hosting an excellent Climate Action Speaker Series. On October 12th, the speaker series featured opening remarks by Senator Liz Lovelett, followed by Jay Kimball, Vice &hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.opalco.com\/es\/accion-climatica\/2023\/10\/\" \/>\n<meta property=\"og:site_name\" content=\"OPALCO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/orcaspower\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-13T18:56:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-13T18:56:49+00:00\" \/>\n<meta name=\"author\" content=\"Krista Bouchey\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OrcasPower\" \/>\n<meta name=\"twitter:site\" content=\"@orcaspower\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Krista Bouchey\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.opalco.com\\\/climate-action\\\/2023\\\/10\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opalco.com\\\/climate-action\\\/2023\\\/10\\\/\"},\"author\":{\"name\":\"Krista Bouchey\",\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#\\\/schema\\\/person\\\/750b0927e29d323ac7fe27a0b3db48d4\"},\"headline\":\"Climate Action in San Juan County\",\"datePublished\":\"2023-10-13T18:56:09+00:00\",\"dateModified\":\"2023-10-13T18:56:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.opalco.com\\\/climate-action\\\/2023\\\/10\\\/\"},\"wordCount\":402,\"publisher\":{\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#organization\"},\"articleSection\":[\"Energy Policy\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.opalco.com\\\/climate-action\\\/2023\\\/10\\\/\",\"url\":\"https:\\\/\\\/www.opalco.com\\\/climate-action\\\/2023\\\/10\\\/\",\"name\":\"Climate Action in San Juan County - OPALCO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#website\"},\"datePublished\":\"2023-10-13T18:56:09+00:00\",\"dateModified\":\"2023-10-13T18:56:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.opalco.com\\\/climate-action\\\/2023\\\/10\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.opalco.com\\\/climate-action\\\/2023\\\/10\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.opalco.com\\\/climate-action\\\/2023\\\/10\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.opalco.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Climate Action in San Juan County\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#website\",\"url\":\"https:\\\/\\\/www.opalco.com\\\/\",\"name\":\"OPALCO\",\"description\":\"Orcas Power &amp; Light Co-op\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.opalco.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#organization\",\"name\":\"Orcas Power & Light Cooperative\",\"url\":\"https:\\\/\\\/www.opalco.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.opalco.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/09-full-color-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.opalco.com\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/09-full-color-logo.jpg\",\"width\":788,\"height\":624,\"caption\":\"Orcas Power & Light Cooperative\"},\"image\":{\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/orcaspower\",\"https:\\\/\\\/x.com\\\/orcaspower\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.opalco.com\\\/#\\\/schema\\\/person\\\/750b0927e29d323ac7fe27a0b3db48d4\",\"name\":\"Krista Bouchey\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55520213b4e552fa8135f4e16078d94b4ff2df5da73caf284df5a1280b02195a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55520213b4e552fa8135f4e16078d94b4ff2df5da73caf284df5a1280b02195a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/55520213b4e552fa8135f4e16078d94b4ff2df5da73caf284df5a1280b02195a?s=96&d=mm&r=g\",\"caption\":\"Krista Bouchey\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/OrcasPower\"],\"url\":\"https:\\\/\\\/www.opalco.com\\\/es\\\/author\\\/kbouchey\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acci\u00f3n Clim\u00e1tica en el Condado de San Juan - OPALCO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.opalco.com\/es\/accion-climatica\/2023\/10\/","og_locale":"es_ES","og_type":"article","og_title":"Climate Action in San Juan County - OPALCO","og_description":"The Madrona Institute has been hosting an excellent Climate Action Speaker Series. On October 12th, the speaker series featured opening remarks by Senator Liz Lovelett, followed by Jay Kimball, Vice &hellip; Read more","og_url":"https:\/\/www.opalco.com\/es\/accion-climatica\/2023\/10\/","og_site_name":"OPALCO","article_publisher":"https:\/\/www.facebook.com\/orcaspower","article_published_time":"2023-10-13T18:56:09+00:00","article_modified_time":"2023-10-13T18:56:49+00:00","author":"Krista Bouchey","twitter_card":"summary_large_image","twitter_creator":"@OrcasPower","twitter_site":"@orcaspower","twitter_misc":{"Written by":"Krista Bouchey","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.opalco.com\/climate-action\/2023\/10\/#article","isPartOf":{"@id":"https:\/\/www.opalco.com\/climate-action\/2023\/10\/"},"author":{"name":"Krista Bouchey","@id":"https:\/\/www.opalco.com\/#\/schema\/person\/750b0927e29d323ac7fe27a0b3db48d4"},"headline":"Climate Action in San Juan County","datePublished":"2023-10-13T18:56:09+00:00","dateModified":"2023-10-13T18:56:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.opalco.com\/climate-action\/2023\/10\/"},"wordCount":402,"publisher":{"@id":"https:\/\/www.opalco.com\/#organization"},"articleSection":["Energy Policy"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/www.opalco.com\/climate-action\/2023\/10\/","url":"https:\/\/www.opalco.com\/climate-action\/2023\/10\/","name":"Acci\u00f3n Clim\u00e1tica en el Condado de San Juan - OPALCO","isPartOf":{"@id":"https:\/\/www.opalco.com\/#website"},"datePublished":"2023-10-13T18:56:09+00:00","dateModified":"2023-10-13T18:56:49+00:00","breadcrumb":{"@id":"https:\/\/www.opalco.com\/climate-action\/2023\/10\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.opalco.com\/climate-action\/2023\/10\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.opalco.com\/climate-action\/2023\/10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.opalco.com\/"},{"@type":"ListItem","position":2,"name":"Climate Action in San Juan County"}]},{"@type":"WebSite","@id":"https:\/\/www.opalco.com\/#website","url":"https:\/\/www.opalco.com\/","name":"OPALCO","description":"Cooperativa de energ\u00eda y luz Orcas","publisher":{"@id":"https:\/\/www.opalco.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.opalco.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.opalco.com\/#organization","name":"Cooperativa de energ\u00eda y luz Orcas","url":"https:\/\/www.opalco.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.opalco.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.opalco.com\/wp-content\/uploads\/2015\/10\/09-full-color-logo.jpg","contentUrl":"https:\/\/www.opalco.com\/wp-content\/uploads\/2015\/10\/09-full-color-logo.jpg","width":788,"height":624,"caption":"Orcas Power & Light Cooperative"},"image":{"@id":"https:\/\/www.opalco.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/orcaspower","https:\/\/x.com\/orcaspower"]},{"@type":"Person","@id":"https:\/\/www.opalco.com\/#\/schema\/person\/750b0927e29d323ac7fe27a0b3db48d4","name":"Krista Bouchey","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/55520213b4e552fa8135f4e16078d94b4ff2df5da73caf284df5a1280b02195a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/55520213b4e552fa8135f4e16078d94b4ff2df5da73caf284df5a1280b02195a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55520213b4e552fa8135f4e16078d94b4ff2df5da73caf284df5a1280b02195a?s=96&d=mm&r=g","caption":"Krista Bouchey"},"sameAs":["https:\/\/x.com\/OrcasPower"],"url":"https:\/\/www.opalco.com\/es\/author\/kbouchey\/"}]}},"_links":{"self":[{"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/posts\/20370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/comments?post=20370"}],"version-history":[{"count":2,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/posts\/20370\/revisions"}],"predecessor-version":[{"id":20374,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/posts\/20370\/revisions\/20374"}],"wp:attachment":[{"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/media?parent=20370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/categories?post=20370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/tags?post=20370"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}