{"id":16886,"date":"2019-04-17T21:46:57","date_gmt":"2019-04-18T04:46:57","guid":{"rendered":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/"},"modified":"2019-04-17T21:46:57","modified_gmt":"2019-04-18T04:46:57","slug":"opalco-recibe-58-millones-para-financiar-proyectos-de-eficiencia-energetica-de-sus-miembros","status":"publish","type":"post","link":"https:\/\/www.opalco.com\/es\/opalco-recibe-58-millones-para-financiar-proyectos-de-eficiencia-energetica-de-sus-miembros\/2019\/04\/","title":{"rendered":"\u00a1OPALCO recibi\u00f3 $5.8M para financiar proyectos de eficiencia energ\u00e9tica de sus miembros!"},"content":{"rendered":"<p><strong>\u00a1Enci\u00e9ndelo! devuelve miles de d\u00f3lares a los bolsillos de los miembros<\/strong><\/p>\n<p>\u00a1OPALCO ahora ofrece financiamiento en la factura para los miembros que quieran cambiarlo! e instale bombas de calor sin ductos, calentadores de agua con bomba de calor y cargadores de veh\u00edculos el\u00e9ctricos s\u00faper eficientes. Estas mejoras pueden reducir a la mitad el gasto de energ\u00eda para calefacci\u00f3n y transporte, en comparaci\u00f3n con los combustibles f\u00f3siles (propano, gasolina), ahorrando miles de d\u00f3lares durante la vida del proyecto y al mismo tiempo reduciendo las emisiones de carbono en nuestro sensible medio ambiente.<\/p>\n<p>Sin pago inicial, los miembros pueden realizar mejoras importantes en su hogar o negocio que crear\u00e1n m\u00e1s comodidad durante todo el a\u00f1o y aumentar\u00e1n el valor de la propiedad. En la mayor\u00eda de los casos, el gasto total de energ\u00eda de un miembro ser\u00e1 menor cada mes, incluso mientras realiza pagos financieros en su factura de energ\u00eda. \u00a1Enci\u00e9ndelo! Los proyectos incluyen:<\/p>\n<ol>\n<li>Bombas de calor sin ductos: Financia hasta $15,000 por hasta 10 a\u00f1os<\/li>\n<li>Calentador de agua con bomba de calor: financie hasta $3,500 por hasta 5 a\u00f1os<\/li>\n<li>Cargador para veh\u00edculos el\u00e9ctricos: financie hasta $2500 durante hasta 3 a\u00f1os<\/li>\n<\/ol>\n<p>Los ahorros variar\u00e1n seg\u00fan el proyecto, pero los miembros que lo cambien. de los combustibles f\u00f3siles obtendr\u00e1n los mayores resultados. Una bomba de calor sin ductos puede reducir el gasto en calefacci\u00f3n a la mitad y ahorrar miles de d\u00f3lares durante la vida del proyecto. Los calentadores de agua con bomba de calor utilizan 60% menos de energ\u00eda y ahorran un promedio de $300 por a\u00f1o, o casi $4000 durante una vida \u00fatil t\u00edpica (13 a\u00f1os).<\/p>\n<p>Si bien los cargadores de veh\u00edculos el\u00e9ctricos son la medida m\u00e1s peque\u00f1a de este programa, cambiar de un veh\u00edculo de gasolina a uno el\u00e9ctrico genera algunos de los mayores ahorros. Conducir un autom\u00f3vil a gasolina representa 53% del uso de energ\u00eda promedio de un residente del condado de San Juan. Un conductor t\u00edpico de una isla ahorrar\u00e1 al menos $1000 cada a\u00f1o en cambios de combustible y aceite, sin mencionar los costos de mantenimiento y reparaci\u00f3n evitados. Con un cargador para veh\u00edculos el\u00e9ctricos de nivel 2, se necesitan entre 4 y 6 horas para cargar completamente un autom\u00f3vil el\u00e9ctrico, lo que cuesta alrededor de $5.60 (dependiendo de la autonom\u00eda de su autom\u00f3vil). Con un alcance t\u00edpico de 120 a 230 millas por carga, \u00bfcon qu\u00e9 frecuencia tendr\u00eda que cargar? Calcule sus ahorros estimados:<\/p>\n<p><a href=\"https:\/\/energysavings.opalco.com\/energy-savings\/electric-vehicles-evs\/savings\/\">https:\/\/energysavings.opalco.com\/energy-savings\/electric-vehicles-evs\/savings\/<\/a>. Los veh\u00edculos el\u00e9ctricos producen aproximadamente 200 veces menos gases de efecto invernadero por milla que un autom\u00f3vil que funciona con combustibles f\u00f3siles. Los veh\u00edculos el\u00e9ctricos marcan una gran diferencia en cuanto a aire y agua limpios.<\/p>\n<p>Los miembros de la cooperativa califican seg\u00fan su historial crediticio con OPALCO (\u00bfpaga su factura a tiempo?). \u00a1Puedes cambiarlo! no importa cu\u00e1les sean sus fuentes de calefacci\u00f3n actuales: propano, z\u00f3calo el\u00e9ctrico, aire forzado, madera o aceite, etc. \u00bfNo est\u00e1 seguro de qu\u00e9 tan bien funcionar\u00e1 para usted o si tiene un proyecto \u00fanico? Contactanos en <a href=\"mailto:energysavings@opalco.com\">energysavings@opalco.com<\/a>.<\/p>\n<p>Es f\u00e1cil de aplicar:<\/p>\n<ol>\n<li>Obtenga una oferta de un contratista. OPALCO tiene una lista de contratistas familiarizados con Switch it Up! en l\u00ednea en <a href=\"https:\/\/www.opalco.com\/es\/reembolsos\/\">www.opalco.com\/rebates\/<\/a>.<\/li>\n<li>Aplica online. <a href=\"https:\/\/www.opalco.com\/es\/switchitup\/\">www.opalco.com\/switchitup<\/a>.<\/li>\n<li>OPALCO revisa las solicitudes r\u00e1pidamente y puede enviarle una carta de aprobaci\u00f3n en 10 a 15 d\u00edas.<\/li>\n<li>Con su carta de aprobaci\u00f3n en mano: firme y devuelva el acuerdo \u2013 \u00a1y luego instale su medida!<\/li>\n<li>El contratista factura directamente a OPALCO.<\/li>\n<li>OPALCO paga al contratista y env\u00eda a los miembros un acuerdo de conservaci\u00f3n que establece los ahorros esperados, los cargos financieros y el plazo.<\/li>\n<\/ol>\n<p>Obtenga m\u00e1s informaci\u00f3n, calcule su Switch it Up estimado! ahorros y aplicar en l\u00ednea en <a href=\"https:\/\/www.opalco.com\/es\/switchitup\/\">www.opalco.com\/switchitup<\/a>.<\/p>\n<p>El financiamiento para este proyecto proviene del Programa de Ahorro de Energ\u00eda Rural (RESP) del USDA. El inter\u00e9s (2%) que se cobra sobre los acuerdos de financiaci\u00f3n garantiza que los costos recaigan en los participantes de este programa, no en la membres\u00eda general. Los proyectos de financiaci\u00f3n en factura est\u00e1n disponibles mientras duren los fondos de RESP.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Enci\u00e9ndelo! devuelve miles de d\u00f3lares a los bolsillos de los miembros \u00a1OPALCO ahora ofrece financiamiento en la factura para los miembros que quieran cambiarlo! e instalar bombas de calor sin conductos s\u00faper eficientes, calefacci\u00f3n\u2026 <a class=\"co-blog_post--morelink\" href=\"https:\/\/www.opalco.com\/es\/opalco-recibe-58-millones-para-financiar-proyectos-de-eficiencia-energetica-de-sus-miembros\/2019\/04\/\" aria-label=\"Lea m\u00e1s sobre: \u00a1OPALCO recibi\u00f3 $5.8M para financiar proyectos de eficiencia energ\u00e9tica de sus miembros!\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":1,"featured_media":16887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[643,651,644,652,46,650],"tags":[],"class_list":["post-16886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ask-opalco","category-ductless-heat-pumps","category-energy-efficiency-conservation","category-energy-tips","category-renewable-energy","category-save-money-and-electricity"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPALCO Awarded $5.8M to Fund Member Energy Efficiency Projects! - OPALCO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.opalco.com\/es\/opalco-recibe-58-millones-para-financiar-proyectos-de-eficiencia-energetica-de-sus-miembros\/2019\/04\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPALCO Awarded $5.8M to Fund Member Energy Efficiency Projects! - OPALCO\" \/>\n<meta property=\"og:description\" content=\"Switch it Up! puts thousands back in members\u2019 pockets OPALCO is now offering on-bill financing for members who want to Switch it Up! and install super-efficient ductless heat pumps, heat &hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.opalco.com\/es\/opalco-recibe-58-millones-para-financiar-proyectos-de-eficiencia-energetica-de-sus-miembros\/2019\/04\/\" \/>\n<meta property=\"og:site_name\" content=\"OPALCO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/orcaspower\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-18T04:46:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1490\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"TbbA27cHc4gWvY2u\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@orcaspower\" \/>\n<meta name=\"twitter:site\" content=\"@orcaspower\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"TbbA27cHc4gWvY2u\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/\"},\"author\":{\"name\":\"TbbA27cHc4gWvY2u\",\"@id\":\"https:\/\/www.opalco.com\/#\/schema\/person\/0d98211a47eeab737dec98e69c2e4c06\"},\"headline\":\"OPALCO Awarded $5.8M to Fund Member Energy Efficiency Projects!\",\"datePublished\":\"2019-04-18T04:46:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/\"},\"wordCount\":572,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.opalco.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg\",\"articleSection\":[\"Ask OPALCO\",\"Ductless Heat Pumps\",\"Energy Efficiency &amp; Conservation\",\"Energy Tips\",\"Renewable Energy\",\"Save Money and Electricity\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/\",\"url\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/\",\"name\":\"OPALCO Awarded $5.8M to Fund Member Energy Efficiency Projects! - OPALCO\",\"isPartOf\":{\"@id\":\"https:\/\/www.opalco.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg\",\"datePublished\":\"2019-04-18T04:46:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#primaryimage\",\"url\":\"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg\",\"contentUrl\":\"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg\",\"width\":1800,\"height\":1490},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.opalco.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPALCO Awarded $5.8M to Fund Member Energy Efficiency Projects!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.opalco.com\/#website\",\"url\":\"https:\/\/www.opalco.com\/\",\"name\":\"OPALCO\",\"description\":\"Orcas Power &amp; Light Co-op\",\"publisher\":{\"@id\":\"https:\/\/www.opalco.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.opalco.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.opalco.com\/#organization\",\"name\":\"Orcas Power & Light Cooperative\",\"url\":\"https:\/\/www.opalco.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.opalco.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.opalco.com\/wp-content\/uploads\/2015\/10\/09-full-color-logo.jpg\",\"contentUrl\":\"https:\/\/www.opalco.com\/wp-content\/uploads\/2015\/10\/09-full-color-logo.jpg\",\"width\":788,\"height\":624,\"caption\":\"Orcas Power & Light Cooperative\"},\"image\":{\"@id\":\"https:\/\/www.opalco.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/orcaspower\",\"https:\/\/x.com\/orcaspower\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.opalco.com\/#\/schema\/person\/0d98211a47eeab737dec98e69c2e4c06\",\"name\":\"TbbA27cHc4gWvY2u\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/9298464b0eb9131ab803ba75771d45eb2f70d3bd56c5efe5d435ef6348507334?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9298464b0eb9131ab803ba75771d45eb2f70d3bd56c5efe5d435ef6348507334?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9298464b0eb9131ab803ba75771d45eb2f70d3bd56c5efe5d435ef6348507334?s=96&d=mm&r=g\",\"caption\":\"TbbA27cHc4gWvY2u\"},\"url\":\"https:\/\/www.opalco.com\/es\/author\/tbba27chc4gwvy2u\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1OPALCO recibi\u00f3 $5.8M para financiar proyectos de eficiencia energ\u00e9tica de sus miembros! - OPALCO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.opalco.com\/es\/opalco-recibe-58-millones-para-financiar-proyectos-de-eficiencia-energetica-de-sus-miembros\/2019\/04\/","og_locale":"es_ES","og_type":"article","og_title":"OPALCO Awarded $5.8M to Fund Member Energy Efficiency Projects! - OPALCO","og_description":"Switch it Up! puts thousands back in members\u2019 pockets OPALCO is now offering on-bill financing for members who want to Switch it Up! and install super-efficient ductless heat pumps, heat &hellip; Read more","og_url":"https:\/\/www.opalco.com\/es\/opalco-recibe-58-millones-para-financiar-proyectos-de-eficiencia-energetica-de-sus-miembros\/2019\/04\/","og_site_name":"OPALCO","article_publisher":"https:\/\/www.facebook.com\/orcaspower","article_published_time":"2019-04-18T04:46:57+00:00","og_image":[{"width":1800,"height":1490,"url":"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg","type":"image\/jpeg"}],"author":"TbbA27cHc4gWvY2u","twitter_card":"summary_large_image","twitter_creator":"@orcaspower","twitter_site":"@orcaspower","twitter_misc":{"Written by":"TbbA27cHc4gWvY2u","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#article","isPartOf":{"@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/"},"author":{"name":"TbbA27cHc4gWvY2u","@id":"https:\/\/www.opalco.com\/#\/schema\/person\/0d98211a47eeab737dec98e69c2e4c06"},"headline":"OPALCO Awarded $5.8M to Fund Member Energy Efficiency Projects!","datePublished":"2019-04-18T04:46:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/"},"wordCount":572,"commentCount":0,"publisher":{"@id":"https:\/\/www.opalco.com\/#organization"},"image":{"@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#primaryimage"},"thumbnailUrl":"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg","articleSection":["Ask OPALCO","Ductless Heat Pumps","Energy Efficiency &amp; Conservation","Energy Tips","Renewable Energy","Save Money and Electricity"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/","url":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/","name":"\u00a1OPALCO recibi\u00f3 $5.8M para financiar proyectos de eficiencia energ\u00e9tica de sus miembros! - OPALCO","isPartOf":{"@id":"https:\/\/www.opalco.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#primaryimage"},"image":{"@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#primaryimage"},"thumbnailUrl":"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg","datePublished":"2019-04-18T04:46:57+00:00","breadcrumb":{"@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#primaryimage","url":"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg","contentUrl":"https:\/\/www.opalco.com\/wp-content\/uploads\/2022\/05\/Streamside-and-Bio-DHP-Install.jpg","width":1800,"height":1490},{"@type":"BreadcrumbList","@id":"https:\/\/www.opalco.com\/opalco-awarded-5-8m-to-fund-member-energy-efficiency-projects\/2019\/04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.opalco.com\/"},{"@type":"ListItem","position":2,"name":"OPALCO Awarded $5.8M to Fund Member Energy Efficiency Projects!"}]},{"@type":"WebSite","@id":"https:\/\/www.opalco.com\/#website","url":"https:\/\/www.opalco.com\/","name":"OPALCO","description":"Cooperativa de energ\u00eda y luz Orcas","publisher":{"@id":"https:\/\/www.opalco.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.opalco.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.opalco.com\/#organization","name":"Cooperativa de energ\u00eda y luz Orcas","url":"https:\/\/www.opalco.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.opalco.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.opalco.com\/wp-content\/uploads\/2015\/10\/09-full-color-logo.jpg","contentUrl":"https:\/\/www.opalco.com\/wp-content\/uploads\/2015\/10\/09-full-color-logo.jpg","width":788,"height":624,"caption":"Orcas Power & Light Cooperative"},"image":{"@id":"https:\/\/www.opalco.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/orcaspower","https:\/\/x.com\/orcaspower"]},{"@type":"Person","@id":"https:\/\/www.opalco.com\/#\/schema\/person\/0d98211a47eeab737dec98e69c2e4c06","name":"TbbA27cHc4gWvY2u","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/9298464b0eb9131ab803ba75771d45eb2f70d3bd56c5efe5d435ef6348507334?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9298464b0eb9131ab803ba75771d45eb2f70d3bd56c5efe5d435ef6348507334?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9298464b0eb9131ab803ba75771d45eb2f70d3bd56c5efe5d435ef6348507334?s=96&d=mm&r=g","caption":"TbbA27cHc4gWvY2u"},"url":"https:\/\/www.opalco.com\/es\/author\/tbba27chc4gwvy2u\/"}]}},"_links":{"self":[{"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/posts\/16886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/comments?post=16886"}],"version-history":[{"count":0,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/posts\/16886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/media\/16887"}],"wp:attachment":[{"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/media?parent=16886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/categories?post=16886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opalco.com\/es\/wp-json\/wp\/v2\/tags?post=16886"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}